{"id":102823,"date":"2021-03-29T11:38:25","date_gmt":"2021-03-29T09:38:25","guid":{"rendered":"https:\/\/www.marbour.eu\/?p=102823"},"modified":"2021-03-29T11:38:36","modified_gmt":"2021-03-29T09:38:36","slug":"arriva-nei-supermercati-il-primo-sacchetto-flessibile-e-riciclabile-di-riso","status":"publish","type":"post","link":"https:\/\/www.marbour.eu\/it\/arriva-nei-supermercati-il-primo-sacchetto-flessibile-e-riciclabile-di-riso\/","title":{"rendered":"Arriva nei supermercati il primo sacchetto flessibile e riciclabile di riso"},"content":{"rendered":"<p>Le dimensioni e la forma del nuovo sacchetto flessibile sono identiche al vecchio equivalente non riciclabile e, secondo i produttori, con le stesse caratteristiche di igiene alimentare e di utilit\u00e0.<\/p>\n<p>I nuovi sacchetti flessibili di riso sono completamente riciclabili e continuano ad offrire la medesima comodit\u00e0 del loro equivalente non riciclabile.<\/p>\n<p>FEI Foods, con sede nel sud del Galles, ha collaborato con J M Packaging per il lancio di un sacchetto flessibile e riciclabile per i prodotti a base di riso da cuocere nel microonde, diventati sempre pi\u00f9 popolari, nelle ultime settimane.<\/p>\n<p>Seppur vero che questi prodotti sono di pi\u00f9 facile utilizzo rispetto al riso crudo da preparare in pentola, numerosi consumatori erano preoccupati che tale comodit\u00e0 generasse una quantit\u00e0 significativa di rifiuti destinati alla discarica. Questo dilemma, ora, pu\u00f2 essere risolto con questo nuovo sacchetto flessibile e riciclabile.<\/p>\n<p>Il sacchetto flessibile \u00e8 fabbricato con quello che viene chiamato un monomateriale, tecnologicamente avanzato, pronto per essere sterilizzato e riciclato, pur conservando tutte le propriet\u00e0 meccaniche di un sacchetto verticale flessibile convenzionale.<br \/>\n\u201cSiamo decisi a fornire il prodotto pi\u00f9 ecoresponsabile possibile e, da diversi anni a questa parte, lo sviluppo di questo sacchetto flessibile \u00e8 uno dei nostri principali obiettivi strategici\u201d, dichiara Simon Lewis, Amministratore Delegato di FEI Foods.<\/p>\n<p>\u201c24 mesi di test rigorosi su questo nuovo materiale hanno portato al lancio di questo prodotto. Siamo lieti ed orgogliosi di essere i primi sul mercato a proporre questa soluzione. Poich\u00e9 la nostra principale attivit\u00e0 \u00e8 la produzione private label, ci\u00f2 rappresenta un risultato straordinario per la nostra azienda, cos\u00ec come per i principali rivenditori al dettaglio, con cui lavoriamo, che ora possono proporre un prodotto pi\u00f9 ecoresponsabile ai loro clienti.\u201d<\/p>\n<p>\u201cAttraverso questo progetto, abbiamo dimostrato il nostro impegno in favore dell\u2019economia circolare, concentrandoci sull\u2019ottimizzazione dell\u2019imballaggio flessibile, per ridurre al minimo l\u2019impatto ambientale, offrendo, allo stesso tempo, al consumatore, comodit\u00e0 ed igiene alimentare\u201d ha affermato Jason McGill, Amministratore Delegato di JMP.<\/p>\n<p>\u201cSiamo orgogliosi di introdurre sul mercato il primo sacchetto monomateriale, pronto per essere riciclato e che pu\u00f2 essere riscaldato, e ringraziamo il nostro team e i partner di FEI Foods per il loro sostegno nella realizzazione di questo progetto.\u201d<\/p>\n<p>I produttori affermano che \u00e8 il primo sacchetto monomateriale, pronto per essere riciclato e che pu\u00f2 essere riscaldato, disponibile nei supermercati del Regno Unito e d\u2019Europa.<\/p>\n<p>Secondo FEI Foods, le dimensioni, la forma e la funzione del sacchetto flessibile rimangono invariate rispetto all\u2019imballaggio attuale, e continuano a corrispondere alle esigenze dei clienti in termini di igiene alimentare, facilit\u00e0 di utilizzo e comodit\u00e0, introducendo, al contempo, rivoluzionari vantaggi ambientali.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le dimensioni e la forma del nuovo sacchetto flessibile sono identiche al vecchio equivalente non riciclabile e, secondo i produttori, con le stesse caratteristiche di igiene alimentare e di utilit\u00e0.I nuovi sacchetti flessibili di riso sono completamente riciclabili e continuano ad offrire la medesima comodit\u00e0 del loro equivalente non riciclabile.<\/p>\n","protected":false},"author":1,"featured_media":102817,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[13],"tags":[],"class_list":["post-102823","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-food-it"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arriva nei supermercati il primo sacchetto flessibile e riciclabile di riso - Marbour<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.marbour.eu\/it\/arriva-nei-supermercati-il-primo-sacchetto-flessibile-e-riciclabile-di-riso\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arriva nei supermercati il primo sacchetto flessibile e riciclabile di riso - Marbour\" \/>\n<meta property=\"og:description\" content=\"Le dimensioni e la forma del nuovo sacchetto flessibile sono identiche al vecchio equivalente non riciclabile e, secondo i produttori, con le stesse caratteristiche di igiene alimentare e di utilit\u00e0.I nuovi sacchetti flessibili di riso sono completamente riciclabili e continuano ad offrire la medesima comodit\u00e0 del loro equivalente non riciclabile.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.marbour.eu\/it\/arriva-nei-supermercati-il-primo-sacchetto-flessibile-e-riciclabile-di-riso\/\" \/>\n<meta property=\"og:site_name\" content=\"Marbour\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/marbour.events\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-29T09:38:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-29T09:38:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.marbour.eu\/wp-content\/uploads\/sachet-riz-recycle.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1274\" \/>\n\t<meta property=\"og:image:height\" content=\"762\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"marbour_admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"marbour_admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.marbour.eu\\\/it\\\/arriva-nei-supermercati-il-primo-sacchetto-flessibile-e-riciclabile-di-riso\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.marbour.eu\\\/it\\\/arriva-nei-supermercati-il-primo-sacchetto-flessibile-e-riciclabile-di-riso\\\/\"},\"author\":{\"name\":\"marbour_admin\",\"@id\":\"https:\\\/\\\/www.marbour.eu\\\/#\\\/schema\\\/person\\\/d95ea8f9f22a5d07fbda7e41767000e2\"},\"headline\":\"Arriva nei supermercati il primo sacchetto flessibile e riciclabile di riso\",\"datePublished\":\"2021-03-29T09:38:25+00:00\",\"dateModified\":\"2021-03-29T09:38:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.marbour.eu\\\/it\\\/arriva-nei-supermercati-il-primo-sacchetto-flessibile-e-riciclabile-di-riso\\\/\"},\"wordCount\":438,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.marbour.eu\\\/it\\\/arriva-nei-supermercati-il-primo-sacchetto-flessibile-e-riciclabile-di-riso\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.marbour.eu\\\/wp-content\\\/uploads\\\/sachet-riz-recycle.jpg\",\"articleSection\":[\"Food\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.marbour.eu\\\/it\\\/arriva-nei-supermercati-il-primo-sacchetto-flessibile-e-riciclabile-di-riso\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.marbour.eu\\\/it\\\/arriva-nei-supermercati-il-primo-sacchetto-flessibile-e-riciclabile-di-riso\\\/\",\"url\":\"https:\\\/\\\/www.marbour.eu\\\/it\\\/arriva-nei-supermercati-il-primo-sacchetto-flessibile-e-riciclabile-di-riso\\\/\",\"name\":\"Arriva nei supermercati il primo sacchetto flessibile e riciclabile di riso - Marbour\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.marbour.eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.marbour.eu\\\/it\\\/arriva-nei-supermercati-il-primo-sacchetto-flessibile-e-riciclabile-di-riso\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.marbour.eu\\\/it\\\/arriva-nei-supermercati-il-primo-sacchetto-flessibile-e-riciclabile-di-riso\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.marbour.eu\\\/wp-content\\\/uploads\\\/sachet-riz-recycle.jpg\",\"datePublished\":\"2021-03-29T09:38:25+00:00\",\"dateModified\":\"2021-03-29T09:38:36+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.marbour.eu\\\/#\\\/schema\\\/person\\\/d95ea8f9f22a5d07fbda7e41767000e2\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.marbour.eu\\\/it\\\/arriva-nei-supermercati-il-primo-sacchetto-flessibile-e-riciclabile-di-riso\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.marbour.eu\\\/it\\\/arriva-nei-supermercati-il-primo-sacchetto-flessibile-e-riciclabile-di-riso\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.marbour.eu\\\/it\\\/arriva-nei-supermercati-il-primo-sacchetto-flessibile-e-riciclabile-di-riso\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.marbour.eu\\\/wp-content\\\/uploads\\\/sachet-riz-recycle.jpg\",\"contentUrl\":\"https:\\\/\\\/www.marbour.eu\\\/wp-content\\\/uploads\\\/sachet-riz-recycle.jpg\",\"width\":1274,\"height\":762},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.marbour.eu\\\/it\\\/arriva-nei-supermercati-il-primo-sacchetto-flessibile-e-riciclabile-di-riso\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.marbour.eu\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Arriva nei supermercati il primo sacchetto flessibile e riciclabile di riso\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.marbour.eu\\\/#website\",\"url\":\"https:\\\/\\\/www.marbour.eu\\\/\",\"name\":\"Marbour\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.marbour.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.marbour.eu\\\/#\\\/schema\\\/person\\\/d95ea8f9f22a5d07fbda7e41767000e2\",\"name\":\"marbour_admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6c9fd8006e31ed7c653ebd93693b0b178af85f2bc5678224f8086dfa80c3e319?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6c9fd8006e31ed7c653ebd93693b0b178af85f2bc5678224f8086dfa80c3e319?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6c9fd8006e31ed7c653ebd93693b0b178af85f2bc5678224f8086dfa80c3e319?s=96&d=mm&r=g\",\"caption\":\"marbour_admin\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arriva nei supermercati il primo sacchetto flessibile e riciclabile di riso - Marbour","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.marbour.eu\/it\/arriva-nei-supermercati-il-primo-sacchetto-flessibile-e-riciclabile-di-riso\/","og_locale":"it_IT","og_type":"article","og_title":"Arriva nei supermercati il primo sacchetto flessibile e riciclabile di riso - Marbour","og_description":"Le dimensioni e la forma del nuovo sacchetto flessibile sono identiche al vecchio equivalente non riciclabile e, secondo i produttori, con le stesse caratteristiche di igiene alimentare e di utilit\u00e0.I nuovi sacchetti flessibili di riso sono completamente riciclabili e continuano ad offrire la medesima comodit\u00e0 del loro equivalente non riciclabile.","og_url":"https:\/\/www.marbour.eu\/it\/arriva-nei-supermercati-il-primo-sacchetto-flessibile-e-riciclabile-di-riso\/","og_site_name":"Marbour","article_publisher":"https:\/\/www.facebook.com\/marbour.events","article_published_time":"2021-03-29T09:38:25+00:00","article_modified_time":"2021-03-29T09:38:36+00:00","og_image":[{"width":1274,"height":762,"url":"https:\/\/www.marbour.eu\/wp-content\/uploads\/sachet-riz-recycle.jpg","type":"image\/jpeg"}],"author":"marbour_admin","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"marbour_admin","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.marbour.eu\/it\/arriva-nei-supermercati-il-primo-sacchetto-flessibile-e-riciclabile-di-riso\/#article","isPartOf":{"@id":"https:\/\/www.marbour.eu\/it\/arriva-nei-supermercati-il-primo-sacchetto-flessibile-e-riciclabile-di-riso\/"},"author":{"name":"marbour_admin","@id":"https:\/\/www.marbour.eu\/#\/schema\/person\/d95ea8f9f22a5d07fbda7e41767000e2"},"headline":"Arriva nei supermercati il primo sacchetto flessibile e riciclabile di riso","datePublished":"2021-03-29T09:38:25+00:00","dateModified":"2021-03-29T09:38:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.marbour.eu\/it\/arriva-nei-supermercati-il-primo-sacchetto-flessibile-e-riciclabile-di-riso\/"},"wordCount":438,"commentCount":0,"image":{"@id":"https:\/\/www.marbour.eu\/it\/arriva-nei-supermercati-il-primo-sacchetto-flessibile-e-riciclabile-di-riso\/#primaryimage"},"thumbnailUrl":"https:\/\/www.marbour.eu\/wp-content\/uploads\/sachet-riz-recycle.jpg","articleSection":["Food"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.marbour.eu\/it\/arriva-nei-supermercati-il-primo-sacchetto-flessibile-e-riciclabile-di-riso\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.marbour.eu\/it\/arriva-nei-supermercati-il-primo-sacchetto-flessibile-e-riciclabile-di-riso\/","url":"https:\/\/www.marbour.eu\/it\/arriva-nei-supermercati-il-primo-sacchetto-flessibile-e-riciclabile-di-riso\/","name":"Arriva nei supermercati il primo sacchetto flessibile e riciclabile di riso - Marbour","isPartOf":{"@id":"https:\/\/www.marbour.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.marbour.eu\/it\/arriva-nei-supermercati-il-primo-sacchetto-flessibile-e-riciclabile-di-riso\/#primaryimage"},"image":{"@id":"https:\/\/www.marbour.eu\/it\/arriva-nei-supermercati-il-primo-sacchetto-flessibile-e-riciclabile-di-riso\/#primaryimage"},"thumbnailUrl":"https:\/\/www.marbour.eu\/wp-content\/uploads\/sachet-riz-recycle.jpg","datePublished":"2021-03-29T09:38:25+00:00","dateModified":"2021-03-29T09:38:36+00:00","author":{"@id":"https:\/\/www.marbour.eu\/#\/schema\/person\/d95ea8f9f22a5d07fbda7e41767000e2"},"breadcrumb":{"@id":"https:\/\/www.marbour.eu\/it\/arriva-nei-supermercati-il-primo-sacchetto-flessibile-e-riciclabile-di-riso\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.marbour.eu\/it\/arriva-nei-supermercati-il-primo-sacchetto-flessibile-e-riciclabile-di-riso\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.marbour.eu\/it\/arriva-nei-supermercati-il-primo-sacchetto-flessibile-e-riciclabile-di-riso\/#primaryimage","url":"https:\/\/www.marbour.eu\/wp-content\/uploads\/sachet-riz-recycle.jpg","contentUrl":"https:\/\/www.marbour.eu\/wp-content\/uploads\/sachet-riz-recycle.jpg","width":1274,"height":762},{"@type":"BreadcrumbList","@id":"https:\/\/www.marbour.eu\/it\/arriva-nei-supermercati-il-primo-sacchetto-flessibile-e-riciclabile-di-riso\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.marbour.eu\/it\/"},{"@type":"ListItem","position":2,"name":"Arriva nei supermercati il primo sacchetto flessibile e riciclabile di riso"}]},{"@type":"WebSite","@id":"https:\/\/www.marbour.eu\/#website","url":"https:\/\/www.marbour.eu\/","name":"Marbour","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.marbour.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.marbour.eu\/#\/schema\/person\/d95ea8f9f22a5d07fbda7e41767000e2","name":"marbour_admin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/6c9fd8006e31ed7c653ebd93693b0b178af85f2bc5678224f8086dfa80c3e319?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6c9fd8006e31ed7c653ebd93693b0b178af85f2bc5678224f8086dfa80c3e319?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6c9fd8006e31ed7c653ebd93693b0b178af85f2bc5678224f8086dfa80c3e319?s=96&d=mm&r=g","caption":"marbour_admin"}}]}},"_links":{"self":[{"href":"https:\/\/www.marbour.eu\/it\/wp-json\/wp\/v2\/posts\/102823","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.marbour.eu\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.marbour.eu\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.marbour.eu\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.marbour.eu\/it\/wp-json\/wp\/v2\/comments?post=102823"}],"version-history":[{"count":2,"href":"https:\/\/www.marbour.eu\/it\/wp-json\/wp\/v2\/posts\/102823\/revisions"}],"predecessor-version":[{"id":102825,"href":"https:\/\/www.marbour.eu\/it\/wp-json\/wp\/v2\/posts\/102823\/revisions\/102825"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.marbour.eu\/it\/wp-json\/wp\/v2\/media\/102817"}],"wp:attachment":[{"href":"https:\/\/www.marbour.eu\/it\/wp-json\/wp\/v2\/media?parent=102823"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.marbour.eu\/it\/wp-json\/wp\/v2\/categories?post=102823"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.marbour.eu\/it\/wp-json\/wp\/v2\/tags?post=102823"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}